{"id":16601,"date":"2021-06-25T08:52:14","date_gmt":"2021-06-25T06:52:14","guid":{"rendered":"https:\/\/www.belca.es\/en\/?p=16601"},"modified":"2022-05-16T09:53:28","modified_gmt":"2022-05-16T07:53:28","slug":"whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film","status":"publish","type":"post","link":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/","title":{"rendered":"Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16601\" class=\"elementor elementor-16601\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46898ab8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46898ab8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b5a31c5\" data-id=\"5b5a31c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc4594c elementor-widget elementor-widget-global elementor-global-5543 elementor-widget-breadcrumbs\" data-id=\"dc4594c\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.belca.es\/en\/\">Home<\/a><\/span><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d91be4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d91be4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b75f02\" data-id=\"4b75f02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f14d65 elementor-widget elementor-widget-heading\" data-id=\"6f14d65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Whole frozen octopus packaging in SP 100 HR INOX and BR03 film<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-971eecc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"971eecc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68a7e6b\" data-id=\"68a7e6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-944938d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"944938d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-20542d0\" data-id=\"20542d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a12d8f1 elementor-aspect-ratio-169 elementor-widget elementor-widget-video\" data-id=\"a12d8f1\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/0B2n6icP2Zg&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;,&quot;aspect_ratio&quot;:&quot;169&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-fit-aspect-ratio elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e61bf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e61bf5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-447f5d1\" data-id=\"447f5d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62f2ecf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62f2ecf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dcd8a1f\" data-id=\"dcd8a1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-424b896 elementor-widget elementor-widget-heading\" data-id=\"424b896\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Description<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5536898 elementor-widget elementor-widget-text-editor\" data-id=\"5536898\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Flow-pack packaging in second skin of whole frozen octopus with SP 100 HR INOX and BR03 polyolefin film.<\/p><p>The SP 100 H range is made up of flow-pack machines with a lower reel made of stainless steel and specially designed for second-skin bagging of food products.<\/p><p>With approaching belt in the cross section for the processing of products of short length or irregular shape and drive of the transverse sealer by means of a servo motor.<\/p><p>The range of applications of these units is very wide due to their characteristic of not having pushers that limit the length of the product and due to the dimensions of the cross section.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad24942 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ad24942\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-994b703 elementor-widget elementor-widget-heading\" data-id=\"994b703\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Products used<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beeb013 elementor-posts--align-left elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"beeb013\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2966 post type-post status-publish format-standard has-post-thumbnail hentry category-flow-pack tag-airtight tag-flow-pack tag-flowpack tag-hffs tag-horizontal tag-in-line-vacuum tag-map tag-modified-atmosphere tag-second-skin tag-skin-pack tag-synchronized tag-tight-closure tag-tray tag-vacuum\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.belca.es\/en\/soluciones-de-envase\/maquinas-envasado\/flow-pack\/flow-pack-inox-sp100hr\/\" ><div class=\"elementor-post__thumbnail\"><img width=\"300\" height=\"218\" src=\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/sp-100-h-ret-inox-300x218.jpg\" class=\"attachment-medium size-medium\" alt=\"Flowpack SP 100 H RET INOX\" loading=\"lazy\" srcset=\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/sp-100-h-ret-inox-300x218.jpg 300w, https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/sp-100-h-ret-inox-768x557.jpg 768w, https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/sp-100-h-ret-inox.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.belca.es\/en\/soluciones-de-envase\/maquinas-envasado\/flow-pack\/flow-pack-inox-sp100hr\/\" >\n\t\t\t\tSP 100 H RET INOX flow wrapper\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-3036 post type-post status-publish format-standard has-post-thumbnail hentry category-tuneles-retraccion tag-oven tag-shrink tag-shrink-tunnel tag-shrink-wrapper\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.belca.es\/en\/soluciones-de-envase\/maquinas-envasado\/tuneles-retraccion\/tunel-de-retraccion-btv\/\" ><div class=\"elementor-post__thumbnail\"><img width=\"300\" height=\"218\" src=\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/btv-45-plus-300x218.jpg\" class=\"attachment-medium size-medium\" alt=\"TUNEL BTV 45 PLUS\" loading=\"lazy\" srcset=\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/btv-45-plus-300x218.jpg 300w, https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/btv-45-plus-768x557.jpg 768w, https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/07\/btv-45-plus.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.belca.es\/en\/soluciones-de-envase\/maquinas-envasado\/tuneles-retraccion\/tunel-de-retraccion-btv\/\" >\n\t\t\t\tBTV Shrink Tunnel\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edd36b1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"edd36b1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e1cb62 elementor-widget elementor-widget-heading\" data-id=\"7e1cb62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">More application sectors<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d2b902 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d2b902\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-701956a\" data-id=\"701956a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4cb70 elementor-widget elementor-widget-image\" data-id=\"3b4cb70\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/en\/soluciones-de-envase\/aplicaciones\/industria-alimentaria\/congelado\">\n\t\t\t\t\t\t\t<img width=\"150\" height=\"150\" src=\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/05\/130-3-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Aplicaciones de alimentaci\u00f3n: pescado, carne, marisco congelado\" loading=\"lazy\" srcset=\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/05\/130-3.png 150w, https:\/\/www.belca.es\/en\/wp-content\/uploads\/2020\/05\/130-3-90x90.png 90w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a6d652a\" data-id=\"a6d652a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-d67e9d6\" data-id=\"d67e9d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-031ed4d\" data-id=\"031ed4d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-aa582e9\" data-id=\"aa582e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-565c1f9\" data-id=\"565c1f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30227a8\" data-id=\"30227a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1eeeb6 elementor-button-align-center elementor-widget elementor-widget-global elementor-global-2344 elementor-widget-form\" data-id=\"c1eeeb6\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Formulario Maquinas\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"16601\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c1eeeb6\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"BELCA\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-html elementor-field-group elementor-column elementor-field-group-field_0177265 elementor-col-100\">\n\t\t\t\t\tRequest information about the Product:\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-maquina elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[maquina]\" id=\"form-field-maquina\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Name\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Email\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-telefono elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-telefono\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelephone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[telefono]\" id=\"form-field-telefono\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Telephone\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-pais elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-pais\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCountry\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[pais]\" id=\"form-field-pais\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Country\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-provincia elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-provincia\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tProvincie\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[provincia]\" id=\"form-field-provincia\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Province \/ State\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-empresa elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-empresa\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCompany\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[empresa]\" id=\"form-field-empresa\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Company\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"1\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-privacidad elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[privacidad]\" id=\"form-field-privacidad\" class=\"elementor-field elementor-size-xs  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-privacidad\"><span style=\"color:#ffffff;\">I have read and accept the <a href=\"\/privacidad\" target=\"_new\" style=\"color:#ffffff;\">Privacy Policy<\/a><\/span><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_7b2628a elementor-col-100 recaptcha_v3-bottomleft\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_7b2628a\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcKMrQZAAAAAM4413UJyISyV8DwRVYMzzdCRfOH\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomleft\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm elementor-animation-grow\" id=\"send\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8d305c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8d305c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abe1421\" data-id=\"abe1421\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eefe692 elementor-widget elementor-widget-text-editor\" data-id=\"eefe692\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: right;\">Guidance specifications, may not be up to date. Please, request more information through the contact form.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9c7f0a elementor-widget elementor-widget-html\" data-id=\"d9c7f0a\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script language=\"javascript\">\n\n  document.getElementById(\"cambiolang\").href = \"https:\/\/www.belca.es\/aplicacion-video-envase\/alimentacion\/congelado\/envasado-pulpo-entero-congelado-flow-pack-sp100hr-film-br03\/\";\n\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Flow-pack packaging in second skin of whole frozen whole octopus with SP 100 HR LH INOX and BR03 polyolefin film.<\/p>\n","protected":false},"author":1,"featured_media":16602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":[],"categories":[121],"tags":[1587,1610,1306,71,262,1302,1490,1466,2003,1589,1611,1465,1420],"wf_post_folders":[1987],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film - BELCA<\/title>\n<meta name=\"description\" content=\"Flow-pack packaging in second skin of whole frozen whole octopus with SP 100 HR LH INOX and BR03 polyolefin film.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"direccion_am2fv2rx\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.belca.es\/en\/#website\",\"url\":\"https:\/\/www.belca.es\/en\/\",\"name\":\"BELCA\",\"description\":\"Packaging systems for Food and Industrial Sectors: design, manufacture and services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.belca.es\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#primaryimage\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2021\/06\/pulpo-sp100hr-btvplus-210623.jpg\",\"contentUrl\":\"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2021\/06\/pulpo-sp100hr-btvplus-210623.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#webpage\",\"url\":\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/\",\"name\":\"Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film - BELCA\",\"isPartOf\":{\"@id\":\"https:\/\/www.belca.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#primaryimage\"},\"datePublished\":\"2021-06-25T06:52:14+00:00\",\"dateModified\":\"2022-05-16T07:53:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.belca.es\/en\/#\/schema\/person\/ea8f8f53c59475fe6e5a3d03d6a96397\"},\"description\":\"Flow-pack packaging in second skin of whole frozen whole octopus with SP 100 HR LH INOX and BR03 polyolefin film.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.belca.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video applications\",\"item\":\"https:\/\/www.belca.es\/en\/category\/aplicacion-video-envase\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Food Applications\",\"item\":\"https:\/\/www.belca.es\/en\/category\/aplicacion-video-envase\/alimentacion\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Frozen fish and meat\",\"item\":\"https:\/\/www.belca.es\/en\/category\/aplicacion-video-envase\/alimentacion\/congelado\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.belca.es\/en\/#\/schema\/person\/ea8f8f53c59475fe6e5a3d03d6a96397\",\"name\":\"direccion_am2fv2rx\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.belca.es\/en\/#personlogo\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6200270f54bb3565d3809fcc4a35088a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6200270f54bb3565d3809fcc4a35088a?s=96&d=mm&r=g\",\"caption\":\"direccion_am2fv2rx\"},\"url\":\"https:\/\/www.belca.es\/en\/author\/direccion_am2fv2rx\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film - BELCA","description":"Flow-pack packaging in second skin of whole frozen whole octopus with SP 100 HR LH INOX and BR03 polyolefin film.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/","twitter_misc":{"Written by":"direccion_am2fv2rx","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.belca.es\/en\/#website","url":"https:\/\/www.belca.es\/en\/","name":"BELCA","description":"Packaging systems for Food and Industrial Sectors: design, manufacture and services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belca.es\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"ImageObject","@id":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#primaryimage","inLanguage":"en-GB","url":"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2021\/06\/pulpo-sp100hr-btvplus-210623.jpg","contentUrl":"https:\/\/www.belca.es\/en\/wp-content\/uploads\/2021\/06\/pulpo-sp100hr-btvplus-210623.jpg","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#webpage","url":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/","name":"Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film - BELCA","isPartOf":{"@id":"https:\/\/www.belca.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#primaryimage"},"datePublished":"2021-06-25T06:52:14+00:00","dateModified":"2022-05-16T07:53:28+00:00","author":{"@id":"https:\/\/www.belca.es\/en\/#\/schema\/person\/ea8f8f53c59475fe6e5a3d03d6a96397"},"description":"Flow-pack packaging in second skin of whole frozen whole octopus with SP 100 HR LH INOX and BR03 polyolefin film.","breadcrumb":{"@id":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.belca.es\/en\/aplicacion-video-envase\/alimentacion\/congelado\/whole-frozen-octopus-packaging-flow-pack-sp100hr-br03-film\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belca.es\/en\/"},{"@type":"ListItem","position":2,"name":"Video applications","item":"https:\/\/www.belca.es\/en\/category\/aplicacion-video-envase\/"},{"@type":"ListItem","position":3,"name":"Food Applications","item":"https:\/\/www.belca.es\/en\/category\/aplicacion-video-envase\/alimentacion\/"},{"@type":"ListItem","position":4,"name":"Frozen fish and meat","item":"https:\/\/www.belca.es\/en\/category\/aplicacion-video-envase\/alimentacion\/congelado\/"},{"@type":"ListItem","position":5,"name":"Whole frozen octopus packaging in flow-pack SP 100 HR LH INOX and BR03 film"}]},{"@type":"Person","@id":"https:\/\/www.belca.es\/en\/#\/schema\/person\/ea8f8f53c59475fe6e5a3d03d6a96397","name":"direccion_am2fv2rx","image":{"@type":"ImageObject","@id":"https:\/\/www.belca.es\/en\/#personlogo","inLanguage":"en-GB","url":"https:\/\/secure.gravatar.com\/avatar\/6200270f54bb3565d3809fcc4a35088a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6200270f54bb3565d3809fcc4a35088a?s=96&d=mm&r=g","caption":"direccion_am2fv2rx"},"url":"https:\/\/www.belca.es\/en\/author\/direccion_am2fv2rx\/"}]}},"_links":{"self":[{"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/posts\/16601"}],"collection":[{"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/comments?post=16601"}],"version-history":[{"count":11,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/posts\/16601\/revisions"}],"predecessor-version":[{"id":18720,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/posts\/16601\/revisions\/18720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/media\/16602"}],"wp:attachment":[{"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/media?parent=16601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/categories?post=16601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/tags?post=16601"},{"taxonomy":"wf_post_folders","embeddable":true,"href":"https:\/\/www.belca.es\/en\/wp-json\/wp\/v2\/wf_post_folders?post=16601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}